{"id":1495,"date":"2023-05-05T21:41:46","date_gmt":"2023-05-05T23:41:46","guid":{"rendered":"https:\/\/www.sebastienpla.com\/PLA\/?p=1495"},"modified":"2023-05-26T14:08:28","modified_gmt":"2023-05-26T12:08:28","slug":"apprentis-citoyens-un-tres-beau","status":"publish","type":"post","link":"https:\/\/www.sebastienpla.com\/PLA\/2023\/05\/05\/apprentis-citoyens-un-tres-beau\/","title":{"rendered":"\u00ab Apprentis citoyens \u00bb : des jeunes de Narbonne en visite au S\u00e9nat"},"content":{"rendered":"<p>\u00ab Apprentis citoyens \u00bb : un tr\u00e8s beau projet men\u00e9 par les Espaces Jeunes de L&rsquo;Arche \u00e0 #Narbonne ! Cette association d&rsquo;\u00c9ducation Populaire narbonnaise, constitu\u00e9e en Maison de Quartier \u00e0 Saint Jean \u2013 Saint Pierre, avec le soutien de la Ville de Narbonne et du Grand Narbonne, du D\u00e9partement de l&rsquo;Aude, de la CAF, et de l&rsquo;ANCT, organise un \u00ab road trip \u00bb en mini van \u00e0 la rencontre des institutions : locales, mais aussi nationales et internationales, puisque leur voyage se poursuit \u00e0 Strasbourg, Bruxelles et Gen\u00e8ve&#8230; J&rsquo;ai eu \u00e0 cette occasion le plaisir de recevoir une quinzaine de jeunes \u00e0 Paris cette semaine, pour une visite du S\u00e9nat &#8211; Palais du Luxembourg et une pr\u00e9sentation de cette institution parlementaire majeure mais mal connue. S&rsquo;en est suivi un temps de discussions informel mais dense, puisqu&rsquo;ils m&rsquo;avaient pr\u00e9par\u00e9 de nombreuses questions, sur mon parcours scolaire, la fonction de S\u00e9nateur, la vie politique&#8230; Un \u00e9chang\u00e9 tr\u00e8s int\u00e9ressant qui m&rsquo;a permis de leur expliquer que gr\u00e2ce \u00e0 la R\u00e9publique, tout est possible, quelque soit son parcours de vie ou son origine sociale ! Bravo pour cette initiative, et bonne route \u00e0 ces jeunes citoyens&#8230;<\/p>\n<div id='gallery-1' class='gallery galleryid-1495 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sebastienpla.com\/PLA\/344899772_804654370742100_1273456219476093531_n_625678502913198\/'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/344899772_804654370742100_1273456219476093531_n_625678502913198-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/344899772_804654370742100_1273456219476093531_n_625678502913198-300x225.jpg 300w, https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/344899772_804654370742100_1273456219476093531_n_625678502913198-1024x768.jpg 1024w, https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/344899772_804654370742100_1273456219476093531_n_625678502913198-768x576.jpg 768w, https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/344899772_804654370742100_1273456219476093531_n_625678502913198-320x240.jpg 320w, https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/344899772_804654370742100_1273456219476093531_n_625678502913198-480x360.jpg 480w, https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/344899772_804654370742100_1273456219476093531_n_625678502913198-800x600.jpg 800w, https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/344899772_804654370742100_1273456219476093531_n_625678502913198.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Apprentis citoyens \u00bb : un tr\u00e8s beau projet men\u00e9 par les Espaces Jeunes de L&rsquo;Arche \u00e0 #Narbonne ! Cette [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00ab Apprentis citoyens \u00bb : des jeunes de Narbonne en visite au S\u00e9nat - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab Apprentis citoyens \u00bb : des jeunes de Narbonne en visite au S\u00e9nat - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude\" \/>\n<meta property=\"og:description\" content=\"\u00ab Apprentis citoyens \u00bb : un tr\u00e8s beau projet men\u00e9 par les Espaces Jeunes de L&rsquo;Arche \u00e0 #Narbonne ! Cette [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-05T23:41:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-26T12:08:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/345212782_6937427106287095_2575012887341872944_n_625678519579863.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SP_Matthieu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"SP_Matthieu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/\",\"url\":\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/\",\"name\":\"\u00ab Apprentis citoyens \u00bb : des jeunes de Narbonne en visite au S\u00e9nat - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude\",\"isPartOf\":{\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/#website\"},\"datePublished\":\"2023-05-05T23:41:46+00:00\",\"dateModified\":\"2023-05-26T12:08:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/#\/schema\/person\/4e26a35bae6b77cf885f58b4c82c4058\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.sebastienpla.com\/PLA\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab Apprentis citoyens \u00bb : des jeunes de Narbonne en visite au S\u00e9nat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/#website\",\"url\":\"https:\/\/www.sebastienpla.com\/PLA\/\",\"name\":\"S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude\",\"description\":\"S\u00e9nateur de l&#039;Aude\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sebastienpla.com\/PLA\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/#\/schema\/person\/4e26a35bae6b77cf885f58b4c82c4058\",\"name\":\"SP_Matthieu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bbf841924758c34b15ae6eae3d5bf409a81f499e3c2acddfb0922b24d981f731?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bbf841924758c34b15ae6eae3d5bf409a81f499e3c2acddfb0922b24d981f731?s=96&d=mm&r=g\",\"caption\":\"SP_Matthieu\"},\"url\":\"https:\/\/www.sebastienpla.com\/PLA\/author\/sp_matthieu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab Apprentis citoyens \u00bb : des jeunes de Narbonne en visite au S\u00e9nat - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"\u00ab Apprentis citoyens \u00bb : des jeunes de Narbonne en visite au S\u00e9nat - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","og_description":"\u00ab Apprentis citoyens \u00bb : un tr\u00e8s beau projet men\u00e9 par les Espaces Jeunes de L&rsquo;Arche \u00e0 #Narbonne ! Cette [&hellip;]","og_url":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/","og_site_name":"S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","article_published_time":"2023-05-05T23:41:46+00:00","article_modified_time":"2023-05-26T12:08:28+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.sebastienpla.com\/PLA\/wp-content\/uploads\/2023\/04-05-FB\/345212782_6937427106287095_2575012887341872944_n_625678519579863.jpg","type":"image\/jpeg"}],"author":"SP_Matthieu","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"SP_Matthieu","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/","url":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/","name":"\u00ab Apprentis citoyens \u00bb : des jeunes de Narbonne en visite au S\u00e9nat - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","isPartOf":{"@id":"https:\/\/www.sebastienpla.com\/PLA\/#website"},"datePublished":"2023-05-05T23:41:46+00:00","dateModified":"2023-05-26T12:08:28+00:00","author":{"@id":"https:\/\/www.sebastienpla.com\/PLA\/#\/schema\/person\/4e26a35bae6b77cf885f58b4c82c4058"},"breadcrumb":{"@id":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sebastienpla.com\/PLA\/"},{"@type":"ListItem","position":2,"name":"\u00ab Apprentis citoyens \u00bb : des jeunes de Narbonne en visite au S\u00e9nat"}]},{"@type":"WebSite","@id":"https:\/\/www.sebastienpla.com\/PLA\/#website","url":"https:\/\/www.sebastienpla.com\/PLA\/","name":"S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","description":"S\u00e9nateur de l&#039;Aude","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sebastienpla.com\/PLA\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sebastienpla.com\/PLA\/#\/schema\/person\/4e26a35bae6b77cf885f58b4c82c4058","name":"SP_Matthieu","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sebastienpla.com\/PLA\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bbf841924758c34b15ae6eae3d5bf409a81f499e3c2acddfb0922b24d981f731?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bbf841924758c34b15ae6eae3d5bf409a81f499e3c2acddfb0922b24d981f731?s=96&d=mm&r=g","caption":"SP_Matthieu"},"url":"https:\/\/www.sebastienpla.com\/PLA\/author\/sp_matthieu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/posts\/1495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/comments?post=1495"}],"version-history":[{"count":1,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/posts\/1495\/revisions"}],"predecessor-version":[{"id":1528,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/posts\/1495\/revisions\/1528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/media\/1372"}],"wp:attachment":[{"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/media?parent=1495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/categories?post=1495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/tags?post=1495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}