{"id":1562,"date":"2023-06-08T00:39:52","date_gmt":"2023-06-07T22:39:52","guid":{"rendered":"https:\/\/www.sebastienpla.com\/PLA\/?page_id=1562"},"modified":"2024-02-08T13:48:46","modified_gmt":"2024-02-08T12:48:46","slug":"sport","status":"publish","type":"page","link":"https:\/\/www.sebastienpla.com\/PLA\/sport\/","title":{"rendered":"PPL honorabilit\u00e9 dans le sport"},"content":{"rendered":"<p>[vc_row][vc_column width=\u00a0\u00bb1\/1&Prime;][vc_custom_heading css_animation=\u00a0\u00bbsingle-slide\u00a0\u00bb uncode_shortcode_id=\u00a0\u00bb893669&Prime;]Proposition de loi visant \u00e0 renforcer la protection des mineurs et l&rsquo;honorabilit\u00e9 dans le sport[\/vc_custom_heading][vc_column_text uncode_shortcode_id=\u00a0\u00bb812035&Prime;]Apr\u00e8s un long travail pr\u00e9paratif, j\u2019ai d\u00e9pos\u00e9 en 2023 ma premi\u00e8re proposition de loi, qui propose de renforcer les contr\u00f4les de l\u2019honorabilit\u00e9 dans le sport, et de lutter contre les violences sexuelles dans le milieu sportif. Un travail men\u00e9 en collaboration avec la grande sportive Sarah Abitbol, la championne de patinage artistique, premi\u00e8re sportive a avoir bris\u00e9 le mur du silence dans le milieu sportif.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_tabs][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; tab_id=\u00a0\u00bb0c8f63f0-52f4-4&Prime; title=\u00a0\u00bbActualit\u00e9 du texte\u00a0\u00bb][vc_column_text uncode_shortcode_id=\u00a0\u00bb176293&Prime;]<strong>Prochaine \u00e9tape :<\/strong><\/p>\n<p>&#8211; 29 f\u00e9vrier 2024, examen du texte en s\u00e9ance publique \u00e0 l&rsquo;Assembl\u00e9e Nationale<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Historique de ma proposition de loi :<\/strong><\/p>\n<p>&#8211; 14 f\u00e9vrier 2024 : examen du texte en commission des affaires culturelles et de l&rsquo;\u00e9ducation \u00e0 l&rsquo;Assembl\u00e9e Nationale<\/p>\n<p>&#8211; Janvier 2024 : inscription du texte \u00e0 l&rsquo;Assembl\u00e9e Nationale sur la niche parlementaire du groupe Socialistes et apparent\u00e9s<\/p>\n<p>&#8211; 15 Juin 2023 : adoption du texte \u00e0 l&rsquo;unanimit\u00e9, en premi\u00e8re lecture, en s\u00e9ance publique au S\u00e9nat<\/p>\n<p>&#8211; 7 Juin 2023 : examen du texte en commission de la Culture,<br \/>\nde l&rsquo;\u00c9ducation et de la Communication<\/p>\n<p>&#8211; Mai 2023 : inscription du texte sur la niche parlementaire<br \/>\nde mon groupe politique, le groupe Socialistes, \u00c9cologistes et R\u00e9publicains<\/p>\n<p>&#8211; 16 janvier 2023 : d\u00e9p\u00f4t de la Proposition de Loi au S\u00e9nat<\/p>\n<p>&#8211; Novembre 2022 : rencontre au S\u00e9nat avec Sarah Abitbol<\/p>\n<p>&#8211; Mars 2021 : d\u00e9but du travail sur ma proposition de loi[\/vc_column_text][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; title=\u00a0\u00bble constat\u00a0\u00bb tab_id=\u00a0\u00bb1686163262-1-47&Prime;][vc_column_text uncode_shortcode_id=\u00a0\u00bb186942&Prime;]Face \u00e0 l\u2019ampleur du ph\u00e9nom\u00e8ne des violences sexuelles sur les mineurs dans le sport, avec la championne de patinage artistique Sarah Abitbol, nous appelons \u00e0 ce que la honte change de camp par le renforcement de la loi sur la protection des mineurs et l\u2019honorabilit\u00e9 dans le sport, proposition de loi qui sera d\u00e9battue en s\u00e9ance publique le jeudi 15 juin prochain.<\/p>\n<p>Les chiffres sont alarmants, d\u2019apr\u00e8s la Ciivise (Commission ind\u00e9pendante sur l\u2019inceste et les violences sexuelles faites aux enfants) pr\u00e8s de 160 000 enfants sont victimes de violences sexuelles chaque ann\u00e9e, en France. Entre 70 et 85% des enfants connaissent leur agresseur ce qui veut dire que la majorit\u00e9 sont victimes de personnes proches de leur entourage.<\/p>\n<p>Une autre \u00e9tude d\u00e9montre que pr\u00e8s d\u2019un enfant sur cinq est victime de violences sexuelles en Europe (attouchements sexuels, viols, harc\u00e8lement et agressions sexuelles \u2026). Ces agressions subies dans l\u2019enfance ne sont pas sans cons\u00e9quences sur les adultes, qui seront davantage sujets \u00e0 des troubles post traumatiques\u00a0: d\u00e9pressions, troubles alimentaires, du comportement, addictions, errance&#8230;[\/vc_column_text][vc_column_text uncode_shortcode_id=\u00a0\u00bb963681&Prime;]Le monde du sport n\u2019\u00e9chappe pas \u00e0 ce ph\u00e9nom\u00e8ne, dans les faits, on estime qu\u2019un enfant sur sept est victime de violence pr\u00e9cis\u00e9ment, dans le milieu sportif.<\/p>\n<p>Pourquoi le sport fournit un terreau favorable \u00e0 l\u2019apparition de ces violences\u00a0?<\/p>\n<p>\u2022 Parce qu\u2019il existe une grande tol\u00e9rance pour les violences verbales, physiques et les blessures qui poussent les athl\u00e8tes \u00e0 se d\u00e9passer\u00a0;<\/p>\n<p>\u2022 Il existe aussi un leadership autoritaire et un d\u00e9s\u00e9quilibre de rapport de force entre les entraineurs et les athl\u00e8tes peut favoriser les d\u00e9rives\u00a0;<\/p>\n<p>\u2022 De plus, les contacts physiques souvent n\u00e9cessaires et la pratique du syst\u00e8me de r\u00e9compense a tendance \u00e0 museler les victimes, et la pr\u00e9dominance du genre masculin dans le sport peut conduire \u00e0 des abus de position dominante. Il faut aussi reconnaitre que c\u2019est un milieu o\u00f9 les incidents sont facilement \u00e9touff\u00e9s et o\u00f9 l\u2019omerta pr\u00e9domine comme la presse vient encore de le r\u00e9v\u00e9ler r\u00e9cemment\u00a0;<\/p>\n<p>\u2022 Enfin l\u2019organisation structurelle de la pratique sportive engendre des situations \u00e0 risques : je pense aux vestiaires, douches, au co-voiturage, d\u00e9placements, stages, internat, soir\u00e9es festives&#8230;[\/vc_column_text][vc_row_inner limit_content=\u00a0\u00bb\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_single_image media=\u00a0\u00bb1567&Prime; media_width_percent=\u00a0\u00bb100&Prime; uncode_shortcode_id=\u00a0\u00bb132003&Prime;][vc_column_text uncode_shortcode_id=\u00a0\u00bb167635&Prime;]<em><strong>Sarah Abitbol<\/strong><\/em>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text uncode_shortcode_id=\u00a0\u00bb198301&Prime;]Depuis la sortie du livre-t\u00e9moignage de Sarah ABITBOL \u00ab Un si long silence \u00bb en 2020, l\u2019omerta a \u00e9t\u00e9 bris\u00e9e et de nombreuses voix s\u2019\u00e9l\u00e8vent pour d\u00e9noncer des agressions sexuelles et des viols subies dans le cadre sportif. Dans le sillon de la championne de patinage artistique, de la joueuse de tennis Isabelle Demongeot, de l\u2019athl\u00e8te Catherine Moyon de Baecque, du rugbyman S\u00e9bastien BOUEILH, et de toutes celles et ceux qui se sont exprim\u00e9s, cette lib\u00e9ration de la parole des victimes pose la premi\u00e8re pierre de la reconstruction personnelle des sportives et des sportifs.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text uncode_shortcode_id=\u00a0\u00bb136096&Prime;]Si 43 % des victimes ont pu mener leur(s) agresseur(s) jusqu\u2019au proc\u00e8s, suivi d\u2019une condamnation force est de constater qu\u2019il reste du chemin \u00e0 faire. Pourquoi ? Par le fait de la prescription bien s\u00fbr, mais aussi parce que les victimes ont honte et peuvent porter une vie durant le fardeau de ce silence. Ce constat je l\u2019ai fait lorsque j\u2019ai rencontr\u00e9 des victimes qui m\u2019ont fait part de leur parcours difficile pour se relever de telles agressions, indigne d\u2019une soci\u00e9t\u00e9 moderne et j\u2019ai \u00e9t\u00e9 le t\u00e9moin indirect des souffrances endur\u00e9es. C\u2019est pourquoi je milite \u00e0 mon tour \u00e0 leurs c\u00f4t\u00e9s pour que \u00ab\u00a0la honte change de camp\u00a0\u00bb.<\/p>\n<p>Nous appelons ainsi, avec des associations de protection de l\u2019enfance, avec des sportifs et personnalit\u00e9s engag\u00e9es, \u00e0 des actes forts pour muscler le cadre l\u00e9gal de la pratique sportive des mineurs, pour rassurer les parents et lever les soup\u00e7ons qui pourraient planer sur les clubs.<\/p>\n<p>La pratique d\u2019un sport est fondamentale pour l\u2019\u00e9panouissement physique et moral, c\u2019est l\u2019\u00e9cole des valeurs de la vie, du vivre ensemble et c\u2019est un puissant vecteur d\u2019\u00e9galit\u00e9.Les pratiques sportives doivent donc \u00eatre sanctuaris\u00e9es et le sport \u00e9thique \u00e9rig\u00e9 en valeur cardinale.[\/vc_column_text][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; tab_id=\u00a0\u00bbc05fd2ee-01f3-5&Prime; title=\u00a0\u00bbun long combat\u00a0\u00bb][vc_column_text uncode_shortcode_id=\u00a0\u00bb103184&Prime;]Il aura fallu pr\u00e8s de deux si\u00e8cles pour que se r\u00e9alise une v\u00e9ritable r\u00e9volution morale : celle de consid\u00e9rer les violences sexuelles sur mineurs non plus comme une offense \u00e0 l\u2019ordre social ou \u00e0 la famille patriarcale mais bien une offense faite \u00e0 la personne humaine.<\/p>\n<p>Depuis le code Napol\u00e9onien et au terme de plus de 20 ans de travaux parlementaires, le nouveau code p\u00e9nal entr\u00e9 en vigueur le 1er mars 1994 a pos\u00e9 le principe fondamental de d\u00e9fense de la personne humaine en la prot\u00e9geant contre toutes les atteintes qui visent son corps, sa libert\u00e9, sa moralit\u00e9, sa dignit\u00e9.<\/p>\n<p>L\u2019arsenal l\u00e9gislatif, depuis, s\u2019est muscl\u00e9. \u00c0 la fin des ann\u00e9es 1990, l\u2019attention a port\u00e9 sur l\u2019identification de ces violences sp\u00e9cifiques \u00a0: p\u00e9dophilie, p\u00e9dopornographie, tourisme sexuel. Parall\u00e8lement, la question de l\u2019imprescriptibilit\u00e9 des crimes sexuels et celle de la r\u00e9tention de s\u00fbret\u00e9 pour les auteurs d\u2019infractions sexuelles ont aussi \u00e9t\u00e9 au c\u0153ur des d\u00e9bats.<\/p>\n<p>Puis, face aux nombreux signalements et au mouvement de lib\u00e9ration de parole des victimes, en 2019, la mission d\u2019information s\u00e9natoriale sur la pr\u00e9vention, la d\u00e9tection et la r\u00e9pression des infractions sexuelles sur les mineurs conduite par nos coll\u00e8gues Catherine Deroche, Michelle Meunier, Marie Mercier et Dominique Verien relevait que \u00ab\u00a0les situations o\u00f9 l\u2019adulte a acc\u00e8s au corps de l`enfant requi\u00e8rent une vigilance toute particuli\u00e8re\u00bb, et appelait \u00e0 un renforcement du contr\u00f4le de l\u2019honorabilit\u00e9 des adultes en contact avec les enfants, en appliquant partout les \u00ab\u00a0standards les plus hauts\u00a0\u00bb.<\/p>\n<p>En 2021, la loi sur les principes de la R\u00e9publique qui introduit un contrat d\u2019engagement r\u00e9publicain pour les associations, a confort\u00e9 l\u2019obligation d\u2019honorabilit\u00e9 dans le milieu sportif. L\u2019article 64 de cette loi a ainsi compl\u00e9t\u00e9 le champ des personnes soumises au contr\u00f4le de l\u2019honorabilit\u00e9 dans le milieu sportif en l\u2019\u00e9tendant \u00e0 toutes les personnes intervenant aupr\u00e8s de mineurs au sein d\u2019\u00e9tablissements dans lesquels sont pratiqu\u00e9es des activit\u00e9s physiques ou sportives.<\/p>\n<p>Le contr\u00f4le de l\u2019\u00c9tat consiste en l\u2019interrogation du casier judiciaire national (bulletin n\u00b0 2), du fichier judiciaire national automatis\u00e9 des auteurs d\u2019infractions sexuelles ou violentes (FIJAIS), mais aussi de la base des cadres interdits qui recense les personnes faisant l\u2019objet d\u2019une mesure de suspension. \u00c0 ces fins, un Syst\u00e8me d\u2019information automatis\u00e9 du contr\u00f4le d\u2019honorabilit\u00e9 des \u00e9ducateurs sportifs et des exploitants d\u2019\u00e9tablissement d\u2019activit\u00e9s physiques et sportives (EAPS) b\u00e9n\u00e9voles disposant d\u2019une licence sportive a \u00e9t\u00e9 mise en place depuis mars 2021.<\/p>\n<p>Mais comment s\u2019assurer que l\u2019ensemble des intervenants aupr\u00e8s des mineurs en milieu sportif, b\u00e9n\u00e9voles, administratifs, parents accompagnateurs n\u2019ont fait l\u2019objet d\u2019aucune condamnation pour des faits d\u2019agression sexuelle\u00a0?<br \/>\nBien que la loi pr\u00e9voie cette obligation d\u2019honorabilit\u00e9, force est de constater qu\u2019il demeure des situations o\u00f9 des adultes sont plac\u00e9s au contact des enfants sans qu\u2019ils fassent peuvent de leur honorabilit\u00e9. Ces derniers ne sont donc pas contr\u00f4l\u00e9s.<\/p>\n<p>Lors de mes diff\u00e9rents \u00e9changes avec les clubs sportifs et ou encore lors des auditions conduites, j\u2019ai aussi constat\u00e9, un r\u00e9el manque d\u2019appropriation de la charte d\u2019honorabilit\u00e9 au sein des clubs. Nombre de pr\u00e9sident de clubs, voire de Ligues, n\u2019avaient une connaissance que tr\u00e8s partielle voire n\u2019\u00e9taient pas sensibilis\u00e9s \u00e0 cette question. Voil\u00e0 qui vient illustrer le manque de clart\u00e9 du message, et probablement in fine que cela interroge aussi le manque d\u2019efficacit\u00e9 des moyens de pr\u00e9vention et de pr\u00e9vention mis \u00e0 disposition des acteurs du sport.<\/p>\n<p>Il peut donc y avoir des pr\u00e9dateurs et pr\u00e9datrices opportunistes qui se glissent dans l\u2019enceinte des clubs de sport et pr\u00e9sentent des dangers pour l\u2019int\u00e9grit\u00e9 des enfants. Il en est de m\u00eame de certains parents qui peuvent venir ponctuellement en soutien lors de manifestations sportives (quand l\u2019on sait que 85% des personnes qui ont subi des violences connaissent leur agresseur cela doit nous interroger\u00a0!)<\/p>\n<p>Le travail engag\u00e9 par le S\u00e9nat et le minist\u00e8re des sports m\u00e9rite d\u2019\u00eatre soulign\u00e9, il a permis de faire progresser le d\u00e9bat, il encourage la lib\u00e9ration de la parole des victimes, mais gardons \u00e0 l\u2019esprit que les dispositifs en vigueur sont encore perfectibles, c\u2019est pourquoi nous devons continuer \u00e0 faire \u0153uvre utile de mani\u00e8re transpartisane, afin de poursuivre ce long chemin pour d\u00e9fendre l\u2019int\u00e9grit\u00e9 de ce que l\u2019on a de plus pr\u00e9cieux\u2026 nos enfants..<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Les principales avanc\u00e9es l\u00e9gislatives sur le sujet\u00a0:<\/strong><\/p>\n<p>\u2022 la loi du 10 juillet 1989<br \/>\nElle pose les bases d\u2019une l\u00e9gislation contre la maltraitance \u00e0 enfant<br \/>\n\u2022 La loi du 17 juin 1998<br \/>\nElle introduit la lutte contre la r\u00e9cidive des infracteurs \u00e0 travers la mise en place du Suivi Socio-Judiciaire (SSJ) et l\u2019inscription au Fichier Judiciaire National Automatis\u00e9 des D\u00e9linquants Sexuels (FIJAIS)<br \/>\n\u2022 la loi du 8 f\u00e9vrier 2010<br \/>\nL\u2019entr\u00e9e du terme d\u2019inceste<br \/>\n\u2022 La loi du 3 ao\u00fbt 2018<br \/>\nElle renforce la lutte contre les violences sexuelles et sexistes qui vise \u00e0 am\u00e9liorer la r\u00e9pression des violences sexistes et qui porte \u00e0 30 ans l\u2019allongement du d\u00e9lais de prescription pour les crimes sexuels commis sur des enfants.[\/vc_column_text][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; title=\u00a0\u00bbnotre proposition\u00a0\u00bb tab_id=\u00a0\u00bb1686163262-2-6&Prime;][vc_column_text uncode_shortcode_id=\u00a0\u00bb548575&Prime;]En l\u2019\u00e9tat actuel de la proc\u00e9dure retenue mise en \u0153uvre par le Minist\u00e8re, les adultes qu\u2019ils soient encadrants ou \u00e9ducateurs sportifs, commencent souvent \u00e0 exercer leurs fonctions avant m\u00eame d\u2019avoir renseign\u00e9 le Syst\u00e8me informatis\u00e9 Honorabilit\u00e9 et que le contr\u00f4le est donc effectu\u00e9 a posteriori.<\/p>\n<p>Je propose d\u2019inverser la charge de la preuve qui p\u00e8se actuellement sur les victimes en la faisant porter par les adultes, en leur demandant d\u2019attester de leur honorabilit\u00e9, avant m\u00eame qu\u2019ils soient au contact de mineurs. C\u2019est aujourd\u2019hui possible par la loi, il s\u2019agit de le rendre obligatoire.<\/p>\n<p>Je souhaite que l\u2019on puisse s\u2019assurer que ce contr\u00f4le soit bien op\u00e9r\u00e9 mais aussi responsabiliser l\u2019ensemble des acteurs du milieu sportif en incitant, chaque club, gr\u00e2ce \u00e0 ce dispositif de double contr\u00f4le, \u00e0 prendre une part active dans la pr\u00e9vention et ainsi \u00e9viter d\u2019exposer les enfants \u00e0 des risques que l\u2019on pourrait mieux anticiper.<\/p>\n<p>Ce texte propose d\u2019agir plus en amont, pour couper l\u2019herbe sous le pied des pr\u00e9dateurs, de faire un pas de plus en inversant la charge de la preuve par l\u2019instauration d\u2019un double contr\u00f4le d\u2019honorabilit\u00e9 a priori de l\u2019ensemble des b\u00e9n\u00e9voles et des salari\u00e9s, en mettant \u00e0 disposition des Pr\u00e9sidents de club et f\u00e9d\u00e9ration un nouvel outil avec l\u2019appui des services de l\u2019\u00c9tat.<\/p>\n<p>Notre objectif ultime est de faire en sorte qu\u2019aucun intervenant en milieu sportif, qui aurait fait l\u2019objet d\u2019une inscription contraire au contact des enfants, ou fait l\u2019objet d\u2019une condamnation qu\u2019il aurait omis de d\u00e9clarer, ne puisse \u00eatre plac\u00e9 au contact des mineurs.<\/p>\n<p>Loin d\u2019alourdir la charge publique, ce texte propose de cumuler les dispositifs de contr\u00f4le de la mani\u00e8re suivante :<\/p>\n<p>1\/ En mettant \u00e0 contribution les dirigeants de club\u00a0: cela consiste \u00e0 effectuer un premier filtre a priori par le responsable de l\u2019\u00e9tablissement sportif, qui devra exiger la production du bulletin n\u00b0 3, avant toute prise de fonction pour toute personne intervenant \u00e0 quelque niveau que ce soit dans une association sportive au contact de mineurs, et quel que soit leur statut\u00a0: adh\u00e9rents, b\u00e9n\u00e9voles, volontaires ou salari\u00e9s.<\/p>\n<p>2\/ Par la r\u00e9alisation d\u2019un second filtre, par le biais du FIJAIS (Fichier judicaire automatis\u00e9 des auteurs d\u2019infractions sexuelles ou violentes) et du bulletin n\u00b0 2 (B2), r\u00e9alis\u00e9 uniquement par l\u2019administration \u00e0 l\u2019appui des informations transmises par les F\u00e9d\u00e9rations au titre de l\u2019article D 131-2-1 du code du sport. Qui ne concerne \u00e0 ce jour uniquement les \u00e9ducateurs et encadrants.<\/p>\n<p>3\/ Enfin je propose aussi d\u2019\u00e9tendre les sanctions d\u00e9j\u00e0 pr\u00e9vues pour les intervenants en accueil collectif de mineurs aux intervenants en milieu associatif sportif, d\u00e8s lors qu\u2019ils manquent \u00e0 leurs obligations d\u2019honorabilit\u00e9.[\/vc_column_text][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; tab_id=\u00a0\u00bb229a0b2c-b484-6&Prime; title=\u00a0\u00bbPerspectives\u00a0\u00bb][vc_column_text uncode_shortcode_id=\u00a0\u00bb138872&Prime;]Personne ne peut ignorer que les pr\u00e9dateurs cherchent \u00e0 aller au contact des mineurs. Il faut que les adultes se responsabilisent, car selon la cellule minist\u00e9rielle qui recense les violences sexuelles dans le sport depuis fin 2021, 1\/2 d\u2019\u00e9ducateurs auront \u00e9t\u00e9 contr\u00f4l\u00e9 (925 000 sur 2 millions de personnes concern\u00e9es).<\/p>\n<p>Le r\u00e9sultat est sans appel, 900 affaires ont \u00e9t\u00e9 signal\u00e9es \u00e0 la cellule, affaires dans lesquelles 84% des victimes sont des mineurs. Il a \u00e9t\u00e9 prononc\u00e9 130 incapacit\u00e9s d\u2019exercer dont 55 incapacit\u00e9s prononc\u00e9es \u00e0 l\u2019\u00e9gard de pr\u00e9sident-entra\u00eeneur de club et 97% d\u2019entre eux sont des d\u2019hommes.<\/p>\n<p>Si ces chiffres peuvent \u00eatre salu\u00e9s, car le dispositif mis en place par le minist\u00e8re \u00e9tait absolument n\u00e9cessaire, il conna\u00eet n\u00e9anmoins quelques failles. Les \u00e9ducateurs sous le coup d\u2019une interdiction d\u2019exercice peuvent demander l\u2019effacement de leur casier B2 par le juge, cela a d\u2019ailleurs g\u00e9n\u00e9r\u00e9 des contentieux avec leur f\u00e9d\u00e9ration.<\/p>\n<p>Sur la responsabilit\u00e9 des dirigeants lors de la fermeture administrative de leur club qui ne sont pas sanctionn\u00e9s et qui peuvent continuer \u00e0 exercer dans une autre association. Je remercie M. le Rapporteur des propositions qu\u2019il fait pour combler ces failles.<\/p>\n<p>Face \u00e0 ce constat, Mme Am\u00e9lie Oueda-Castera, la ministre des sports, pleinement engag\u00e9e pour la cause, dans le sillage de sa pr\u00e9decesseure, Roxana Maracineanu, a d\u2019ores et d\u00e9j\u00e0 annonc\u00e9 vouloir poursuivre cet engagement en doublant les effectifs d\u00e9di\u00e9s du minist\u00e8re pour assurer le contr\u00f4le d\u2019honorabilit\u00e9 dans le prochain projet de loi de finances (PLF 2024), c\u2019est un pas de plus, que je tiens \u00e0 saluer.<\/p>\n<p>Mais, ne nous voilons pas la face, pour assurer la lutte contre les violences il faut des moyens, et le minist\u00e8re des sports ne pourra tout assumer seul, il est aussi n\u00e9cessaire que les f\u00e9d\u00e9rations et les clubs s\u2019engagement plus fortement et s\u2019approprient le sujet car nous ne pouvons faire reposer ce contr\u00f4le que sur un syst\u00e8me informatique.<\/p>\n<p>Nous ne parviendrons \u00e0 relever ce challenge qu\u2019en jouant en \u00e9quipe\u00a0!<\/p>\n<p>M\u00eame si j\u2019ai pleinement conscience des craintes que ce texte peut susciter dans les clubs et associations sportives qui sont confront\u00e9s \u00e0 l\u2019\u00e9rosion du b\u00e9n\u00e9volat, gardons tout de m\u00eame \u00e0 l\u2019esprit que l\u2019esprit de la loi est, avant tout d\u2019\u00e9loigner tout pr\u00e9dateurs sexuels du monde sportif.<\/p>\n<p>Je sais pouvoir compter sur la sagesse du S\u00e9nat pour enrichir par le d\u00e9bat ce texte, pour le faire prosp\u00e9rer. J\u2019ai abord\u00e9 le travail de ce texte avec beaucoup d\u2019humilit\u00e9 et de retenue, en \u00e9tant attentif aux craintes des responsables de clubs et aux t\u00e9moignage des victimes, et je reconnais, que souvent il m\u2019a fallu contenir mes \u00e9motions \u00e0 l\u2019\u00e9coute de ces r\u00e9cits d\u2019horreur et de souffrances.<\/p>\n<p>Alors que la France va tenir dans les jours qui viennent les Assises du sport, qu\u2019elle accueillera la Coupe du monde de Rugby \u00e0 l\u2019automne et les Jeux olympiques de 2024, accompagnons le minist\u00e8re des sports et apportons une pierre suppl\u00e9mentaire \u00e0 cet imposant \u00e9difice de la lutte pour la pr\u00e9vention des violences sexuelles sur mineurs.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Remerciements \u00e0 :<br \/>\n&#8211; M. le Rapporteur Jean Jacques Lozach et son \u00e9quipe\u00a0;<br \/>\n&#8211; Mme l\u2019administratrice Pauline Delignat-Lavaud pour son accompagnement\u00a0;<br \/>\n&#8211; Mes coll\u00e8gues S\u00e9natrices et S\u00e9nateurs, du groupe socialistes du S\u00e9nat et en particulier les soutiens de la premi\u00e8re heure.[\/vc_column_text][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; tab_id=\u00a0\u00bb3b8d4034-341d-2&Prime; title=\u00a0\u00bb\u00c9volutions en commission\u00a0\u00bb][vc_column_text uncode_shortcode_id=\u00a0\u00bb871926&Prime;]La commission de la culture, de l\u2019\u00e9ducation et de la communication du S\u00e9nat, comp\u00e9tente sur ce texte, a examin\u00e9 le 7 juin 2023 la proposition de loi, les d\u00e9bats et la recherche d\u2019un consensus, qui fait la richesse du travail parlementaire, a amen\u00e9 plusieurs modifications du texte.<\/p>\n<p>La commission dans un premier temps a d\u00e9battu et jug\u00e9 que le contr\u00f4le de l\u2019honorabilit\u00e9 doit demeurer une pr\u00e9rogative de l\u2019\u00c9tat. Un contr\u00f4le du bulletin n\u00b03 par les dirigeants de club pourrait \u00eatre per\u00e7u comme un transfert de responsabilit\u00e9. Un dirigeant de club, pourrait de bonne foi, \u00e0 la consultation de l\u2019extrait judiciaire transmis par l\u2019\u00e9ducateur sportif, penser que celui-ci remplit les conditions d\u2019honorabilit\u00e9 sans que cela ne soit juridiquement le cas. Cette disposition n\u2019est donc pas maintenue.<\/p>\n<p>Les membres de la commission ont par ailleurs souhait\u00e9 compl\u00e9ter et renforcer le texte sur plusieurs points :<\/p>\n<p>&#8211; Introduction dans le champ sportif du renforcement du contr\u00f4le d\u2019honorabilit\u00e9, dont a d\u00e9j\u00e0 b\u00e9n\u00e9fici\u00e9 le secteur social et m\u00e9dico-social par la loi Taquet en 2022. L\u2019une des mesures importantes est le fait qu\u2019une inscription d\u2019une condamnation au FIJAIS maintienne l\u2019incapacit\u00e9 d\u2019exercer, m\u00eame si la condamnation a disparu du bulletin n\u00b02 de la personne.<\/p>\n<p>&#8211; mise en place pour les dirigeants de club de l\u2019obligation de signaler au pr\u00e9fet des comportements au sein de leurs clubs pr\u00e9sentant un danger pour la s\u00e9curit\u00e9 ou la sant\u00e9 morale et physique des sportifs.<\/p>\n<p>&#8211; cr\u00e9ation de sanctions administratives, en l\u2019esp\u00e8ce une interdiction d\u2019exercer temporaire ou d\u00e9finitive, envers les dirigeants de clubs sportifs, dans trois cas : lorsqu\u2019il emploie un \u00e9ducateur sportif en m\u00e9connaissance des obligations d\u2019honorabilit\u00e9 ; lorsque le comportement du dirigeant de club fait peser un risque sur la sant\u00e9 des pratiquants ; lorsque, connaissant des faits pr\u00e9sentant un risque pour la sant\u00e9 des pratiquants de son club, il ne les signale pas aux services d\u00e9concentr\u00e9s du minist\u00e8re des sports. \u00c0 noter qu\u2019\u00e0 l\u2019heure actuelle, la seule mesure administrative pouvant \u00eatre prise par le pr\u00e9fet en cas de probl\u00e8me avec un dirigeant est la fermeture du club sportif.[\/vc_column_text][vc_single_image media=\u00a0\u00bb1568&Prime; media_width_percent=\u00a0\u00bb100&Prime; uncode_shortcode_id=\u00a0\u00bb108380&Prime;][vc_column_text uncode_shortcode_id=\u00a0\u00bb190846&Prime;]En conclusion, il a fallu faire quelques concessions au regard des plus hauts standards de protection que nous souhaitions mettre en \u0153uvre (notamment sur le casier B3) ; mais le texte renforcera et s\u00e9curisera le contr\u00f4le d\u2019honorabilit\u00e9, tout en venant renforcer les mesures d\u2019incapacit\u00e9s.<\/p>\n<p>Ces adaptations ont permis une adoption du texte \u00e0 l\u2019unanimit\u00e9 par la commission. Il sera donc d\u00e9battu le 15 juin prochain en s\u00e9ance publique avec un avis favorable de la commission : je m\u2019en r\u00e9jouis !<\/p>\n<p>Nous allons continuer dans l\u2019avenir \u00e0 d\u00e9fendre notre proposition visant \u00e0 mettre en \u0153uvre un double filtrage, faisant \u00e9galement appel au club, et envisager la cr\u00e9ation d\u2019un r\u00e9f\u00e9rent \u00e9thique.<\/p>\n<p>La lutte contre les violences sexuelle et un immense \u00e9difice qui se construit pierre par pierre, nous essayons d\u2019apporter la n\u00f4tre et continuerons, au-del\u00e0 de la s\u00e9ance du 15 juin, \u00e0 porter ce combat ![\/vc_column_text][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; tab_id=\u00a0\u00bb3e27abf7-1627-8&Prime; title=\u00a0\u00bbAdoption au S\u00e9nat\u00a0\u00bb][vc_column_text uncode_shortcode_id=\u00a0\u00bb108669&Prime;]Le 15 juin 2023, le S\u00e9nat a adopt\u00e9 \u00e0 l\u2019unanimit\u00e9 la proposition de loi Sarah Abitbol port\u00e9e par le S\u00e9nateur S\u00e9bastien PLA, au sujet du renforcement la protection des mineurs et de<br \/>\nl&rsquo;honorabilit\u00e9 dans le sport.<\/p>\n<p>Ce texte de loi a pour objectif d\u2019\u00e9loigner les pr\u00e9dateurs, de responsabiliser davantage les dirigeants de club sportif et d\u2019accompagner la lib\u00e9ration de la parole.<\/p>\n<p>Nous appelons \u00e0 ce que la honte et la peur changent de camp.<\/p>\n<p style=\"text-align: right;\"><strong>Sarah Abitbol et S\u00e9bastien Pla<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; tab_id=\u00a0\u00bb0187a6fb-7453-9&Prime; title=\u00a0\u00bb\u00c0 l&rsquo;Assembl\u00e9e Nationale\u00a0\u00bb][vc_column_text uncode_shortcode_id=\u00a0\u00bb138283&Prime;]\u00c0 l\u2019initiative de Claudia Rouaux, d\u00e9put\u00e9e d\u2019Ille-et-Vilaine, les d\u00e9put\u00e9\u00b7e\u00b7s socialistes et apparent\u00e9s ont inscrit \u00e0 l\u2019ordre de jour de l\u2019Assembl\u00e9e nationale lors de leur journ\u00e9e r\u00e9serv\u00e9e du 29 f\u00e9vrier la proposition de loi visant \u00e0 renforcer la protection des mineurs et l\u2019honorabilit\u00e9 dans le sport.<\/p>\n<p>Cette proposition de loi initi\u00e9e par le s\u00e9nateur de l\u2019Aude S\u00e9bastien Pla et les s\u00e9natrices et s\u00e9nateurs du groupe Socialiste, \u00c9cologiste et R\u00e9publicain a \u00e9t\u00e9 adopt\u00e9e \u00e0 l\u2019unanimit\u00e9 en premi\u00e8re lecture au S\u00e9nat le 15 juin dernier, faisant \u00e9cho aux nombreux t\u00e9moignages de sportifs, comme Sarah Abitbol, qui ont eu le courage de briser l\u2019omerta.<\/p>\n<p>La commission d\u2019enqu\u00eate parlementaire sur les dysfonctionnements au sein des f\u00e9d\u00e9rations sportives, notamment en mati\u00e8re de violences sexuelles, pr\u00e9sid\u00e9e par B\u00e9atrice Bellamy et rapport\u00e9e par Sabrina Sebaihi, qui a pr\u00e9sent\u00e9 ses conclusions ce mardi 23 janvier, participe pleinement de cette prise de conscience collective.<\/p>\n<p>Par cette action coordonn\u00e9e, les parlementaires socialistes entendent amplifier la traque des pr\u00e9dateurs sexuels en d\u00e9livrant un message tr\u00e8s fort : le monde du sport doit \u00eatre sanctuaris\u00e9, aucun adulte d\u00e9j\u00e0 condamn\u00e9 pour faits d\u2019agression ou violences sexuelles ne devrait \u00eatre au contact des enfants dans le cadre de la<br \/>\npratique sportive.<\/p>\n<p>Or, le contr\u00f4le de l\u2019honorabilit\u00e9 des encadrants et \u00e9ducateurs sportifs est aujourd\u2019hui un dispositif al\u00e9atoire, qui a r\u00e9v\u00e9l\u00e9 de nombreuses failles exploitables par les auteurs de violences sexuelles. Cette proposition de loi pr\u00e9voit ainsi :<\/p>\n<p>&#8211; De durcir le contr\u00f4le de l\u2019honorabilit\u00e9 des encadrants et des \u00e9ducateurs sportifs en comblant les lacunes des dispositifs existants via la consultation du bulletin n\u00b02 du casier judiciaire (comprenant la quasi-int\u00e9gralit\u00e9 des condamnations judiciaires et sanctions administratives) et du fichier judiciaire automatis\u00e9 des auteurs d\u2019infractions sexuelles ou violentes (FIJAIS)<\/p>\n<p>&#8211; De renforcer les obligations de signalement par les dirigeants de club, des comportements \u00e0 risques pr\u00e9sentant un danger pour la s\u00e9curit\u00e9 et la sant\u00e9 physique ou morale des sportifs et des sportives sauf \u00e0 s\u2019exposer \u00e0 de lourdes sanctions (interdiction d\u2019exercer et de diriger un club sportif, un an d\u2019emprisonnement et 15 000 euros d\u2019amende.)<\/p>\n<p>Ce texte s\u2019inscrit plus globalement dans la continuit\u00e9 d\u2019initiatives port\u00e9es par des<br \/>\nparlementaires socialistes visant \u00e0 mieux prot\u00e9ger les enfants des violences sexuelles.[\/vc_column_text][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; tab_id=\u00a0\u00bbe426f4c5-94d2-3&Prime; title=\u00a0\u00bbLe texte actuel\u00a0\u00bb][vc_column_text uncode_shortcode_id=\u00a0\u00bb337426&Prime;]<\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-style: normal;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: x-large;\"><b>N\u00b0\u00a0700<\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"text-decoration: line-through;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-style: normal;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Georgia;\"><span style=\"font-size: xx-large;\"><b>S\u00c9NAT<\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-style: normal; font-weight: normal;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: small;\">SESSION ORDINAIRE DE 2022-2023<\/span><\/span><\/span><\/p>\n<p style=\"margin-top: 0.18cm; margin-bottom: 0cm; border: none; padding: 0cm;\" align=\"CENTER\"><span style=\"color: #000000;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-style: normal; font-weight: normal;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: xx-small;\">Enregistr\u00e9 \u00e0 la Pr\u00e9sidence du S\u00e9nat le 7 juin 2023<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-style: normal;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: xx-large;\"><b>PROPOSITION DE LOI<\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-weight: normal;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: large;\"><i>visant\u00a0\u00e0\u00a0<\/i><span style=\"font-style: normal;\"><b>renforcer<\/b><\/span><i>\u00a0la\u00a0<\/i><span style=\"font-style: normal;\"><b>protection<\/b><\/span><i>\u00a0des\u00a0<\/i><span style=\"font-style: normal;\"><b>mineurs<\/b><\/span><i>\u00a0et\u00a0l\u2019honorabilit\u00e9\u00a0dans\u00a0le\u00a0<\/i><span style=\"font-style: normal;\"><b>sport<\/b><\/span><i>,<\/i><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-style: normal;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: xx-large;\"><b>TEXTE DE LA COMMISSION<\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-weight: normal;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: small;\"><i>DE LA CULTURE, DE L&rsquo;\u00c9DUCATION ET DE LA COMMUNICATION (1)<\/i><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"text-decoration: line-through;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/span><\/p>\n<p style=\"text-indent: 0.49cm; margin-bottom: 0cm; border: none; padding: 0cm; font-weight: normal;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: xx-small;\"><i>(1) Cette commission est compos\u00e9e de :\u00a0<\/i><span style=\"font-style: normal;\">M. Laurent Lafon<\/span><i>, pr\u00e9sident ;\u00a0<\/i><span style=\"font-style: normal;\">M.\u00a0Max Brisson, Mme\u00a0Laure Darcos, MM.\u00a0St\u00e9phane Piednoir, Michel Savin, Mme\u00a0Sylvie Robert, MM.\u00a0David Assouline, Julien Bargeton, Pierre Ouzoulias, Bernard Fialaire, Jean-Pierre Decool, Mme\u00a0Monique de Marco<\/span><i>, vice-pr\u00e9sidents ;\u00a0<\/i><span style=\"font-style: normal;\">Mmes\u00a0C\u00e9line Boulay-Esp\u00e9ronnier, Else Joseph, Marie-Pierre Monier, Sonia de La Prov\u00f4t\u00e9<\/span><i>, secr\u00e9taires ;\u00a0<\/i><span style=\"font-style: normal;\">MM.\u00a0Maurice Antiste, J\u00e9r\u00e9my Bacchi, Mmes\u00a0Annick Billon, Alexandra Borchio Fontimp, Toine Bourrat, C\u00e9line Brulin, Samantha Cazebonne, M.\u00a0Yan Chantrel, Mme\u00a0Nathalie Delattre, M.\u00a0Thomas Dossus, Mmes\u00a0Sabine Drexler, V\u00e9ronique Del Fabro, Laurence Garnier, M.\u00a0Jacques Grosperrin, Mme\u00a0B\u00e9atrice Gosselin, MM.\u00a0Jean Hingray, Jean-Raymond Hugonet, Claude Kern, Mikaele Kulimoetoke, Michel Laugier, Pierre-Antoine Levi, Jean-Jacques Lozach, Jacques-Bernard Magner, Jean Louis Masson, Mme\u00a0Catherine Morin-Desailly, MM.\u00a0Olivier Paccaud, Damien Regnard, Bruno Retailleau, Mme\u00a0Elsa Schalck, M.\u00a0Lucien Stanzione, Mmes\u00a0Sabine Van Heghe, Anne Ventalon, M.\u00a0C\u00e9dric Vial.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-style: normal;\" align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: small;\"><b>Voir les num\u00e9ros\u00a0:<\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; border: none; padding: 0cm; font-style: normal; font-weight: normal;\" align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman;\"><span style=\"font-size: small;\"><b>S\u00e9nat\u00a0:\u00a0241<\/b>\u00a0et\u00a0<b>699<\/b>\u00a0(2022-2023).<\/span><\/span><\/span><\/p>\n<div id=\"formCorrection:panel:0:table\" dir=\"LTR\">\n<table cellspacing=\"2\" cellpadding=\"3\">\n<tbody>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-size: xx-small;\"><b>Proposition de loi visant \u00e0 renforcer la protection des mineurs et l\u2019honorabilit\u00e9 dans le sport<\/b><\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div id=\"formCorrection:panel:1:table\" dir=\"LTR\">\n<table cellspacing=\"2\" cellpadding=\"3\">\n<tbody>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"CENTER\"><a name=\"tc-1-cell-1-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\"><b>Article 1<span style=\"font-size: xx-small;\">er<\/span><\/b><\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">L\u2019article\u00a0L.\u00a0212-9 du code du sport est ainsi modifi\u00e9\u00a0:<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-1-cell-3-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">1\u00b0\u00a0<i><span style=\"font-weight: normal;\">(nouveau)<\/span><\/i>\u00a0Apr\u00e8s le\u00a0I, il est ins\u00e9r\u00e9 un\u00a0I\u00a0<i>bis<\/i>\u00a0ainsi r\u00e9dig\u00e9\u00a0:<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-1-cell-4-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a0I\u00a0<i>bis<\/i>.\u00a0\u2013\u00a0Le contr\u00f4le annuel des incapacit\u00e9s mentionn\u00e9es au\u00a0I du pr\u00e9sent article est assur\u00e9 par la d\u00e9livrance du bulletin\u00a0n\u00b0\u00a02 du casier judiciaire dans les conditions pr\u00e9vues \u00e0 l\u2019article\u00a0776 du code de proc\u00e9dure p\u00e9nale et par l\u2019acc\u00e8s aux informations contenues dans le fichier judiciaire national automatis\u00e9 des auteurs d\u2019infractions sexuelles ou violentes dans les conditions pr\u00e9vues \u00e0 l\u2019article\u00a0706-53-7 du m\u00eame code.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-1-cell-5-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a0En cas de condamnation, prononc\u00e9e par une juridiction \u00e9trang\u00e8re et pass\u00e9e en force de chose jug\u00e9e, pour une infraction constituant, selon la loi fran\u00e7aise, un crime ou l\u2019un des d\u00e9lits mentionn\u00e9s au\u00a0I du pr\u00e9sent article, le tribunal judiciaire du domicile du condamn\u00e9, statuant en mati\u00e8re correctionnelle, d\u00e9clare, \u00e0 la requ\u00eate du minist\u00e8re public, qu\u2019il y a lieu \u00e0 l\u2019application de l\u2019incapacit\u00e9 d\u2019exercice pr\u00e9vue au pr\u00e9sent article, apr\u00e8s constatation de la r\u00e9gularit\u00e9 et de la l\u00e9galit\u00e9 de la condamnation et l\u2019int\u00e9ress\u00e9 d\u00fbment appel\u00e9 en chambre du conseil.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-1-cell-6-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a0Les personnes faisant l\u2019objet d\u2019une incapacit\u00e9 d\u2019exercice peuvent demander \u00e0 en \u00eatre relev\u00e9es dans les conditions pr\u00e9vues \u00e0 l\u2019article\u00a0132-21 du code p\u00e9nal ainsi qu\u2019aux articles 702-1 et 703 du code de proc\u00e9dure p\u00e9nale. Cette requ\u00eate est port\u00e9e devant la chambre des appels correctionnels de la cour d\u2019appel dans le ressort de laquelle le requ\u00e9rant r\u00e9side lorsque la condamnation r\u00e9sulte d\u2019une condamnation \u00e9trang\u00e8re et qu\u2019il a \u00e9t\u00e9 fait application du deuxi\u00e8me alin\u00e9a du pr\u00e9sent\u00a0I\u00a0<i>bis<\/i>.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-1-cell-7-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a0Par d\u00e9rogation \u00e0 l\u2019article\u00a0133-16 du code p\u00e9nal, les incapacit\u00e9s pr\u00e9vues au pr\u00e9sent article sont applicables en cas de condamnation d\u00e9finitive figurant au fichier judiciaire national automatis\u00e9 des auteurs d\u2019infractions sexuelles ou violentes m\u00eame si cette condamnation n\u2019est plus inscrite au bulletin\u00a0n\u00b0\u00a02 du casier judiciaire.\u00a0\u00bb\u00a0;<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"text-indent: 0.53cm; border: none; padding: 0cm;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">2\u00b0\u00a0<i><span style=\"font-weight: normal;\">(Supprim\u00e9)<\/span><\/i><\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div id=\"formCorrection:panel:2:table\" dir=\"LTR\">\n<table cellspacing=\"2\" cellpadding=\"3\">\n<tbody>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"CENTER\"><a name=\"tc-2-cell-1-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\"><b>Article 2\u00a0<i>(nouveau)<\/i><\/b><\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-2-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">Le code du sport est ainsi modifi\u00e9\u00a0:<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-3-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">1\u00b0\u00a0L\u2019article\u00a0L.\u00a0322-3 est ainsi r\u00e9tabli\u00a0:<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-4-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a0<i><span style=\"font-weight: normal;\">Art.\u00a0L.\u00a0322-3<\/span><\/i>.\u00a0\u2013\u00a0L\u2019autorit\u00e9 administrative peut, par arr\u00eat\u00e9 motiv\u00e9, prononcer l\u2019interdiction d\u2019exercer, \u00e0 titre temporaire ou d\u00e9finitif, la fonction mentionn\u00e9e \u00e0 l\u2019article\u00a0L.\u00a0322-1 \u00e0 l\u2019encontre de toute personne\u00a0:<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-5-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a01\u00b0\u00a0Dont le maintien en activit\u00e9 constituerait un danger pour la sant\u00e9 et la s\u00e9curit\u00e9 physique ou morale des pratiquants\u00a0;<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-6-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a02\u00b0\u00a0Employant ou permettant l\u2019intervention, en m\u00e9connaissance de l\u2019article\u00a0L.\u00a0212-9, de personnes faisant l\u2019objet d\u2019une incapacit\u00e9 d\u2019exercice pr\u00e9vue au m\u00eame article\u00a0L.\u00a0212-9\u00a0;<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-7-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a03\u00b0\u00a0M\u00e9connaissant l\u2019obligation pr\u00e9vue \u00e0 l\u2019article\u00a0L.\u00a0322-4-1 d\u2019informer l\u2019autorit\u00e9 administrative du comportement d\u2019une personne mentionn\u00e9e au\u00a0I de l\u2019article\u00a0L.\u00a0212-9 dont le maintien en activit\u00e9 constituerait un danger pour la sant\u00e9 et la s\u00e9curit\u00e9 physique ou morale des pratiquants.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-8-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a0Cet arr\u00eat\u00e9 est pris apr\u00e8s avis d\u2019une commission comprenant des repr\u00e9sentants de l\u2019\u00c9tat, du mouvement sportif et des diff\u00e9rentes cat\u00e9gories de personnes int\u00e9ress\u00e9es. Toutefois, en cas d\u2019urgence, l\u2019autorit\u00e9 administrative peut, sans consultation de la commission, prononcer une interdiction temporaire d\u2019exercice limit\u00e9e \u00e0 six\u00a0mois. Dans le cas o\u00f9 l\u2019int\u00e9ress\u00e9 fait l\u2019objet de poursuites p\u00e9nales, la mesure d\u2019interdiction temporaire d\u2019exercer aupr\u00e8s de mineurs s\u2019applique jusqu\u2019\u00e0 l\u2019intervention d\u2019une d\u00e9cision d\u00e9finitive rendue par la juridiction comp\u00e9tente.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-9-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a0Un d\u00e9cret en Conseil d\u2019\u00c9tat fixe les conditions d\u2019application du pr\u00e9sent article.\u00a0\u00bb\u00a0;<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-10-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">2\u00b0\u00a0Le\u00a01\u00b0 de l\u2019article\u00a0L.\u00a0322-4 est ainsi r\u00e9tabli\u00a0:<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-11-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a01\u00b0\u00a0D\u2019exploiter soit directement, soit par l\u2019interm\u00e9diaire d\u2019un tiers, un \u00e9tablissement dans lequel sont pratiqu\u00e9es des activit\u00e9s physiques ou sportives en m\u00e9connaissance d\u2019une mesure prise en application de l\u2019article\u00a0L.\u00a0322-3\u00a0;\u00a0\u00bb<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"border: none; padding: 0cm;\" align=\"JUSTIFY\"><a name=\"tc-2-cell-12-0\"><\/a> <span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">3\u00b0\u00a0Apr\u00e8s le m\u00eame article\u00a0L.\u00a0322-4, il est ins\u00e9r\u00e9 un article\u00a0L.\u00a0322-4-1 ainsi r\u00e9dig\u00e9\u00a0:<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#ffffff\">\n<td>\n<p style=\"text-indent: 0.53cm; border: none; padding: 0cm;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-size: xx-small;\">\u00ab\u00a0<i><span style=\"font-weight: normal;\">Art.\u00a0L.\u00a0322-4-1<\/span><\/i>.\u00a0\u2013\u00a0L\u2019exploitant d\u2019un \u00e9tablissement mentionn\u00e9 \u00e0 l\u2019article\u00a0L.\u00a0322-1 est tenu d\u2019informer sans d\u00e9lai l\u2019autorit\u00e9 administrative lorsqu\u2019il a connaissance du comportement d\u2019une personne mentionn\u00e9e au\u00a0I de l\u2019article\u00a0L.\u00a0212-9 dont le maintien en activit\u00e9 constituerait un danger pour la sant\u00e9 et la s\u00e9curit\u00e9 physique ou morale des pratiquants.\u00a0\u00bb<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>[\/vc_column_text][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; tab_id=\u00a0\u00bb060a2e6c-4021-11&Prime; title=\u00a0\u00bbPhotos\u00a0\u00bb][vc_gallery el_id=\u00a0\u00bbgallery-187814&Prime; medias=\u00a0\u00bb1588,1587,1586,1585,1584&Prime; gutter_size=\u00a0\u00bb3&Prime; screen_lg=\u00a0\u00bb1000&Prime; screen_md=\u00a0\u00bb600&Prime; screen_sm=\u00a0\u00bb480&Prime; single_overlay_opacity=\u00a0\u00bb50&Prime; single_padding=\u00a0\u00bb2&Prime; uncode_shortcode_id=\u00a0\u00bb825384&Prime;][\/vc_tab][vc_tab gutter_size=\u00a0\u00bb2&Prime; column_padding=\u00a0\u00bb2&Prime; tab_id=\u00a0\u00bb91b6950c-d3fb-7&Prime; title=\u00a0\u00bbLiens\u00a0\u00bb][vc_column_text uncode_shortcode_id=\u00a0\u00bb189713&Prime;]Dossier l\u00e9gislatif officiel sur le site du S\u00e9nat :<br \/>\n<a href=\"https:\/\/www.senat.fr\/dossier-legislatif\/ppl22-241.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.senat.fr\/dossier-legislatif\/ppl22-241.html<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Dossier l\u00e9gislatif officiel sur le site du S\u00e9nat :<br \/>\n<a href=\"https:\/\/www.assemblee-nationale.fr\/dyn\/16\/dossiers\/DLR5L16N47026\">https:\/\/www.assemblee-nationale.fr\/dyn\/16\/dossiers\/DLR5L16N47026<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019association \u00abLa Voix de Sarah\u00bb met \u00e0 disposition un kit de sensibilisation \u00e0 la lutte contre les violences sexuelles dans le sport, informations et contact sur :<\/p>\n<p><a href=\"http:\/\/www.lavoixdesarah.org\" target=\"_blank\" rel=\"noopener\">www.lavoixdesarah.org<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Le Minist\u00e8re des Sports mets \u00e0 disposition un guide expliquant les proc\u00e9dures actuelles de contr\u00f4le de l\u2019honorabilit\u00e9 des \u00e9ducateurs et exploitants b\u00e9n\u00e9voles licenci\u00e9s des F\u00e9d\u00e9rations, disponible sur son site internet :<\/p>\n<p><a href=\"https:\/\/www.sports.gouv.fr\/sites\/default\/files\/2023-01\/guide-honorabilit-des-b-n-voles-3844.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/www.sports.gouv.fr\/sites\/default\/files\/2023-01\/guide-honorabilit-des-b-n-voles-3844.pdf<\/a>[\/vc_column_text][\/vc_tab][\/vc_tabs][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_single_image media=\u00a0\u00bb1583&Prime; media_width_percent=\u00a0\u00bb100&Prime; uncode_shortcode_id=\u00a0\u00bb177457&Prime;][vc_column_text uncode_shortcode_id=\u00a0\u00bb108117&Prime;]<\/p>\n<p style=\"text-align: right;\"><em><strong>Sarah Abitbol et S\u00e9bastien Pla au S\u00e9nat<\/strong><\/em><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=\u00a0\u00bb1\/1&Prime;][vc_custom_heading css_animation=\u00a0\u00bbsingle-slide\u00a0\u00bb uncode_shortcode_id=\u00a0\u00bb893669&Prime;]Proposition de loi visant \u00e0 renforcer la protection des mineurs et l&rsquo;honorabilit\u00e9 dans le sport[\/vc_custom_heading][vc_column_text uncode_shortcode_id=\u00a0\u00bb812035&Prime;]Apr\u00e8s un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1562","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PPL honorabilit\u00e9 dans le sport - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PPL honorabilit\u00e9 dans le sport - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=\u00a0\u00bb1\/1&Prime;][vc_custom_heading css_animation=\u00a0\u00bbsingle-slide\u00a0\u00bb uncode_shortcode_id=\u00a0\u00bb893669&Prime;]Proposition de loi visant \u00e0 renforcer la protection des mineurs et l&rsquo;honorabilit\u00e9 dans le sport[\/vc_custom_heading][vc_column_text uncode_shortcode_id=\u00a0\u00bb812035&Prime;]Apr\u00e8s un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-08T12:48:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/\",\"url\":\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/\",\"name\":\"PPL honorabilit\u00e9 dans le sport - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude\",\"isPartOf\":{\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/#website\"},\"datePublished\":\"2023-06-07T22:39:52+00:00\",\"dateModified\":\"2024-02-08T12:48:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.sebastienpla.com\/PLA\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PPL honorabilit\u00e9 dans le sport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sebastienpla.com\/PLA\/#website\",\"url\":\"https:\/\/www.sebastienpla.com\/PLA\/\",\"name\":\"S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude\",\"description\":\"S\u00e9nateur de l&#039;Aude\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sebastienpla.com\/PLA\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PPL honorabilit\u00e9 dans le sport - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"PPL honorabilit\u00e9 dans le sport - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","og_description":"[vc_row][vc_column width=\u00a0\u00bb1\/1&Prime;][vc_custom_heading css_animation=\u00a0\u00bbsingle-slide\u00a0\u00bb uncode_shortcode_id=\u00a0\u00bb893669&Prime;]Proposition de loi visant \u00e0 renforcer la protection des mineurs et l&rsquo;honorabilit\u00e9 dans le sport[\/vc_custom_heading][vc_column_text uncode_shortcode_id=\u00a0\u00bb812035&Prime;]Apr\u00e8s un [&hellip;]","og_url":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/","og_site_name":"S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","article_modified_time":"2024-02-08T12:48:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"21 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/","url":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/","name":"PPL honorabilit\u00e9 dans le sport - S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","isPartOf":{"@id":"https:\/\/www.sebastienpla.com\/PLA\/#website"},"datePublished":"2023-06-07T22:39:52+00:00","dateModified":"2024-02-08T12:48:46+00:00","breadcrumb":{"@id":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sebastienpla.com\/PLA\/2023\/04\/29\/manger-local-un-modele-qui-fonctionne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sebastienpla.com\/PLA\/"},{"@type":"ListItem","position":2,"name":"PPL honorabilit\u00e9 dans le sport"}]},{"@type":"WebSite","@id":"https:\/\/www.sebastienpla.com\/PLA\/#website","url":"https:\/\/www.sebastienpla.com\/PLA\/","name":"S\u00e9bastien Pla, S\u00e9nateur de l&#039;Aude","description":"S\u00e9nateur de l&#039;Aude","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sebastienpla.com\/PLA\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/pages\/1562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/comments?post=1562"}],"version-history":[{"count":15,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/pages\/1562\/revisions"}],"predecessor-version":[{"id":1590,"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/pages\/1562\/revisions\/1590"}],"wp:attachment":[{"href":"https:\/\/www.sebastienpla.com\/PLA\/wp-json\/wp\/v2\/media?parent=1562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}